{"id":4283,"date":"2023-12-03T14:12:01","date_gmt":"2023-12-03T14:12:01","guid":{"rendered":"https:\/\/pure.pureit.pw\/corporate\/?page_id=4283"},"modified":"2024-11-07T19:31:05","modified_gmt":"2024-11-07T19:31:05","slug":"our-team","status":"publish","type":"page","link":"https:\/\/pure.pureit.top\/taxadvisor\/our-team\/","title":{"rendered":"Our Team"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4283\" class=\"elementor elementor-4283\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c2fc9d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1c2fc9d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8d67ae4\" data-id=\"8d67ae4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac14bf5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac14bf5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a4b4d6d\" data-id=\"a4b4d6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70bd9af elementor-invisible elementor-widget elementor-widget-sectiontitle\" data-id=\"70bd9af\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"sectiontitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"section-title style-one t_left\">\r\n                 \r\n                        <h5>OUR MANAGEMENT<\/h5>\r\n                \t\t\t\t\r\n\t\t\t\t  \r\n                       <h1>Our Team Member<\/h1>\r\n                \t\t\t\t\r\n\t\t\t\t                 \t\t\t\r\n\t\t\t\t\r\n\t\t\t<\/div>\t\r\n\r\n\t\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0209fda\" data-id=\"0209fda\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31724c8 elementor-invisible elementor-widget elementor-widget-pureit-button\" data-id=\"31724c8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;}\" data-widget_type=\"pureit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t\r\n\t\t\t\t<div class=\"pureit-button-box\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pureit-button\">\r\n\t\t\t\t\t\t<a href=\"#\">\r\n\t\t\t\t\t\t\t<span>All Team<\/span>\r\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" width=\"10px\" height=\"10px\" viewBox=\"1.25 1.25 7 7\" xml:space=\"preserve\"><polygon fill=\"#fff\" points=\"1.25,1.25 1.25,2.25 6.543,2.25 1.25,7.543 1.958,8.25 7.25,2.957 7.25,8.25 8.25,8.25 8.25,1.25 8.25,1.25 \"><\/polygon><\/svg>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-f687237 e-flex e-con-boxed e-con e-parent\" data-id=\"f687237\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4d442d8 e-con-full e-flex e-con e-child\" data-id=\"4d442d8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dfdd56c elementor-invisible elementor-widget elementor-widget-pureitteam\" data-id=\"dfdd56c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"pureitteam.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n        <div class=\"team-single\">\r\n            \r\n            <div class=\"team_thumb\">\r\n                <img decoding=\"async\" src=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/1-6-1.jpg\" alt=\"\">\r\n            <\/div>\r\n            <div class=\"team-content\">\r\n                <h2 class=\"trigger\">\r\n                    Saad Alam                <\/h2>\r\n                <span>CEO<\/span>\r\n\r\n                <!-- Description Show -->\r\n                                <!-- Description Show -->\r\n\r\n            <\/div>\r\n\r\n            <!-- Social Icon -->\r\n                            <div class=\"social-profiles\">\r\n                    <ul>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-facebook-4\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-instagram-logo\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-linkedin-2\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-twitter\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                            <\/ul>\r\n                <\/div>\r\n                        <!-- Social Icon -->\r\n\r\n         <\/div> <!-- Single Team -->\r\n\r\n                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17fa970 e-con-full e-flex e-con e-child\" data-id=\"17fa970\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b177e2f elementor-invisible elementor-widget elementor-widget-pureitteam\" data-id=\"b177e2f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"pureitteam.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n        <div class=\"team-single\">\r\n            \r\n            <div class=\"team_thumb\">\r\n                <img decoding=\"async\" src=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/3-6.jpg\" alt=\"\">\r\n            <\/div>\r\n            <div class=\"team-content\">\r\n                <h2 class=\"trigger\">\r\n                    Jahir Mahmud                <\/h2>\r\n                <span>Senior Developer<\/span>\r\n\r\n                <!-- Description Show -->\r\n                                <!-- Description Show -->\r\n\r\n            <\/div>\r\n\r\n            <!-- Social Icon -->\r\n                            <div class=\"social-profiles\">\r\n                    <ul>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-facebook-4\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-instagram-logo\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-linkedin-2\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-twitter\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                            <\/ul>\r\n                <\/div>\r\n                        <!-- Social Icon -->\r\n\r\n         <\/div> <!-- Single Team -->\r\n\r\n                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ec4dc7 e-con-full e-flex e-con e-child\" data-id=\"9ec4dc7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3649903 elementor-invisible elementor-widget elementor-widget-pureitteam\" data-id=\"3649903\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"pureitteam.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n        <div class=\"team-single\">\r\n            \r\n            <div class=\"team_thumb\">\r\n                <img decoding=\"async\" src=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/5-3.jpg\" alt=\"\">\r\n            <\/div>\r\n            <div class=\"team-content\">\r\n                <h2 class=\"trigger\">\r\n                    Sultana Shirin                <\/h2>\r\n                <span>Web Designer<\/span>\r\n\r\n                <!-- Description Show -->\r\n                                <!-- Description Show -->\r\n\r\n            <\/div>\r\n\r\n            <!-- Social Icon -->\r\n                            <div class=\"social-profiles\">\r\n                    <ul>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-facebook-4\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-instagram-logo\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-linkedin-2\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-twitter\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                            <\/ul>\r\n                <\/div>\r\n                        <!-- Social Icon -->\r\n\r\n         <\/div> <!-- Single Team -->\r\n\r\n                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d93ead e-flex e-con-boxed e-con e-parent\" data-id=\"1d93ead\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-046e733 e-con-full e-flex e-con e-child\" data-id=\"046e733\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d3993f9 elementor-invisible elementor-widget elementor-widget-pureitteam\" data-id=\"d3993f9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"pureitteam.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n        <div class=\"team-single\">\r\n            \r\n            <div class=\"team_thumb\">\r\n                <img decoding=\"async\" src=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/12\/New-Project-9.jpg\" alt=\"\">\r\n            <\/div>\r\n            <div class=\"team-content\">\r\n                <h2 class=\"trigger\">\r\n                    Alex Jhon Martin                <\/h2>\r\n                <span>Senior Developer<\/span>\r\n\r\n                <!-- Description Show -->\r\n                                <!-- Description Show -->\r\n\r\n            <\/div>\r\n\r\n            <!-- Social Icon -->\r\n                            <div class=\"social-profiles\">\r\n                    <ul>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-facebook-4\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-instagram-logo\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-linkedin-2\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-twitter\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                            <\/ul>\r\n                <\/div>\r\n                        <!-- Social Icon -->\r\n\r\n         <\/div> <!-- Single Team -->\r\n\r\n                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69ef997 e-con-full e-flex e-con e-child\" data-id=\"69ef997\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b8f92e0 elementor-invisible elementor-widget elementor-widget-pureitteam\" data-id=\"b8f92e0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"pureitteam.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n        <div class=\"team-single\">\r\n            \r\n            <div class=\"team_thumb\">\r\n                <img decoding=\"async\" src=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/12\/New-Project-4.jpg\" alt=\"\">\r\n            <\/div>\r\n            <div class=\"team-content\">\r\n                <h2 class=\"trigger\">\r\n                    Saima                <\/h2>\r\n                <span>Senior Developer<\/span>\r\n\r\n                <!-- Description Show -->\r\n                                <!-- Description Show -->\r\n\r\n            <\/div>\r\n\r\n            <!-- Social Icon -->\r\n                            <div class=\"social-profiles\">\r\n                    <ul>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-facebook-4\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-instagram-logo\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-linkedin-2\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-twitter\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                            <\/ul>\r\n                <\/div>\r\n                        <!-- Social Icon -->\r\n\r\n         <\/div> <!-- Single Team -->\r\n\r\n                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf5f26d e-con-full e-flex e-con e-child\" data-id=\"bf5f26d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3506ca6 elementor-invisible elementor-widget elementor-widget-pureitteam\" data-id=\"3506ca6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"pureitteam.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n        \r\n        <div class=\"team-single\">\r\n            \r\n            <div class=\"team_thumb\">\r\n                <img decoding=\"async\" src=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/12\/New-Project-3.jpg\" alt=\"\">\r\n            <\/div>\r\n            <div class=\"team-content\">\r\n                <h2 class=\"trigger\">\r\n                    John                <\/h2>\r\n                <span>Web Designer<\/span>\r\n\r\n                <!-- Description Show -->\r\n                                <!-- Description Show -->\r\n\r\n            <\/div>\r\n\r\n            <!-- Social Icon -->\r\n                            <div class=\"social-profiles\">\r\n                    <ul>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-facebook-4\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-instagram-logo\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-linkedin-2\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                                    <li>\r\n                                <a href=\"#\"><i aria-hidden=\"true\" class=\"flaticon flaticon-twitter\"><\/i><\/i><\/a>\r\n                            <\/li>\r\n                                            <\/ul>\r\n                <\/div>\r\n                        <!-- Social Icon -->\r\n\r\n         <\/div> <!-- Single Team -->\r\n\r\n                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4241adf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4241adf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c111eec\" data-id=\"c111eec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cb2ffd elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6cb2ffd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Have a project in mind?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-906a147 elementor-invisible elementor-widget elementor-widget-pureit-button\" data-id=\"906a147\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"pureit-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"pureit-button-box style2\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"pureit-button\">\r\n\t\t\t\t\t\t<a href=\"#\">\r\n\t\t\t\t\t\t\tLet's Talk\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" x=\"0px\" y=\"0px\" width=\"18px\" height=\"18\" viewBox=\"1.25 1.25 7 7\" xml:space=\"preserve\"><polygon points=\"1.25,1.25 1.25,2.25 6.543,2.25 1.25,7.543 1.958,8.25 7.25,2.957 7.25,8.25 8.25,8.25 8.25,1.25 8.25,1.25 \"><\/polygon><\/svg>\t\t\t\t\t\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-85dc86f e-flex e-con-boxed e-con e-parent\" data-id=\"85dc86f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1255c09 e-con-full e-flex e-con e-child\" data-id=\"1255c09\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-405805a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"405805a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"307\" height=\"178\" src=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/1.png\" class=\"attachment-large size-large wp-image-3922\" alt=\"\" srcset=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/1.png 307w, https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/1-300x174.png 300w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b25311c e-con-full e-flex e-con e-child\" data-id=\"b25311c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fc76b1 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"7fc76b1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"307\" height=\"178\" src=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/5.png\" class=\"attachment-large size-large wp-image-3918\" alt=\"\" srcset=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/5.png 307w, https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/5-300x174.png 300w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7de1c96 e-con-full e-flex e-con e-child\" data-id=\"7de1c96\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d02d4b elementor-invisible elementor-widget elementor-widget-image\" data-id=\"5d02d4b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"307\" height=\"178\" src=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/3.png\" class=\"attachment-large size-large wp-image-3921\" alt=\"\" srcset=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/3.png 307w, https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/3-300x174.png 300w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e8011b9 e-con-full e-flex e-con e-child\" data-id=\"e8011b9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-beacf21 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"beacf21\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"307\" height=\"178\" src=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/4.png\" class=\"attachment-large size-large wp-image-3920\" alt=\"\" srcset=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/4.png 307w, https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/4-300x174.png 300w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-277892e e-con-full e-flex e-con e-child\" data-id=\"277892e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aab248f elementor-invisible elementor-widget elementor-widget-image\" data-id=\"aab248f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"307\" height=\"178\" src=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/2.png\" class=\"attachment-large size-large wp-image-3919\" alt=\"\" srcset=\"https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/2.png 307w, https:\/\/pure.pureit.top\/taxadvisor\/wp-content\/uploads\/2023\/11\/2-300x174.png 300w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>OUR MANAGEMENT Our Team Member All Team Saad Alam CEO Jahir Mahmud Senior Developer Sultana Shirin Web Designer Alex Jhon Martin Senior Developer Saima Senior Developer John Web Designer Have a project in mind? Let&#8217;s Talk<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-default.php","meta":{"footnotes":""},"class_list":["post-4283","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/pure.pureit.top\/taxadvisor\/wp-json\/wp\/v2\/pages\/4283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pure.pureit.top\/taxadvisor\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pure.pureit.top\/taxadvisor\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pure.pureit.top\/taxadvisor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pure.pureit.top\/taxadvisor\/wp-json\/wp\/v2\/comments?post=4283"}],"version-history":[{"count":6,"href":"https:\/\/pure.pureit.top\/taxadvisor\/wp-json\/wp\/v2\/pages\/4283\/revisions"}],"predecessor-version":[{"id":4553,"href":"https:\/\/pure.pureit.top\/taxadvisor\/wp-json\/wp\/v2\/pages\/4283\/revisions\/4553"}],"wp:attachment":[{"href":"https:\/\/pure.pureit.top\/taxadvisor\/wp-json\/wp\/v2\/media?parent=4283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}